{"id":3336,"date":"2023-01-11T07:00:00","date_gmt":"2023-01-11T06:00:00","guid":{"rendered":"https:\/\/www.mycard.ch\/?p=3336"},"modified":"2022-12-28T15:06:45","modified_gmt":"2022-12-28T14:06:45","slug":"les-avantages-imbattables-de-votre-carte-de-credit","status":"publish","type":"post","link":"https:\/\/www.mycard.ch\/fr\/les-avantages-imbattables-de-votre-carte-de-credit\/","title":{"rendered":"Les avantages imbattables de votre carte de cr\u00e9dit"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n\t<div class=\"post-lead-holder\">\n\t\t<p>Votre carte de cr\u00e9dit vous ouvre toutes les portes. Elle est depuis toujours la carte de paiement la plus polyvalente et pr\u00e9sente pas mal d&rsquo;avantages par rapport aux autres modes de paiement. Dans cet article, apprenez-en plus sur les prestations exclusives dont vous b\u00e9n\u00e9ficiez uniquement avec votre carte de cr\u00e9dit.<\/p>\n\t<\/div>\n\n\n\n\t<div class=\"post-attribute-holder\">\n\t\t<span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"3\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. de lecture-11.01.2023 \u2013 \n\t\tPhoto: shutterstock\t<\/div>\n\n\n\n<p>Pendant longtemps, de nombreuses fonctions de la carte de cr\u00e9dit lui \u00e9taient exclusivement r\u00e9serv\u00e9es. A pr\u00e9sent, il existe certes des cartes de paiement, des prestations de service et des produits qui reprennent au moins une partie de ces fonctions. Aujourd&rsquo;hui, de nombreuses cartes de d\u00e9bit vous permettent \u00e9galement d&rsquo;effectuer des achats en ligne. Mais votre carte de cr\u00e9dit peut faire beaucoup plus. Il existe encore de bonnes raisons d&rsquo;opter pour la carte de cr\u00e9dit et ses prestations.<\/p>\n\n\n\n<div class=\"wp-block-group grey box has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>Vos avantages en un coup d&rsquo;\u0153il <\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le meilleur accompagnement avant et pendant le voyage<\/li>\n\n\n\n<li>Flexibilit\u00e9 financi\u00e8re lors du r\u00e8glement de vos factures<\/li>\n\n\n\n<li>S\u00e9curit\u00e9 suppl\u00e9mentaire: 30 jours pour contester les transactions<\/li>\n\n\n\n<li>Services suppl\u00e9mentaires: programme de bonus et assurances int\u00e9ressantes<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les avantages de la carte de cr\u00e9dit <\/strong><\/h2>\n\n\n\n<p>Par rapport \u00e0 une carte de d\u00e9bit ou une carte bancaire normale, les paiements par carte de cr\u00e9dit <strong>ne sont pas imm\u00e9diatement d\u00e9bit\u00e9s du compte<\/strong>. Les montants sont regroup\u00e9s et g\u00e9n\u00e9ralement factur\u00e9s une fois par mois (ou directement d\u00e9bit\u00e9s de votre compte). M\u00eame si vous pouvez aujourd&rsquo;hui payer beaucoup de choses en ligne et hors ligne avec la carte de d\u00e9bit \u2013 par exemple, l&rsquo;h\u00f4tel pour les prochaines vacances \u2013 vous avez g\u00e9n\u00e9ralement besoin d&rsquo;une carte de cr\u00e9dit lors du <strong>check-in<\/strong> ou pour <strong>louer une voiture<\/strong>, dont une empreinte sera r\u00e9alis\u00e9e sur place en guise de caution pendant votre s\u00e9jour. Souvent, il vous faut imp\u00e9rativement une carte de cr\u00e9dit pour pouvoir louer une voiture. La carte de cr\u00e9dit est une garantie pour l&rsquo;h\u00f4tel ou la soci\u00e9t\u00e9 de location de voiture. La caution ne sera pas directement d\u00e9bit\u00e9e de votre compte, mais uniquement bloqu\u00e9e sur votre carte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-mid-size\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-1000x562.jpg\" alt=\"\" class=\"wp-image-3326\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-1000x562.jpg 1000w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-300x169.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-1024x576.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-768x432.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-1536x864.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-500x281.jpg 500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668-1500x843.jpg 1500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_shopping_16x9_1417347668.jpg 1600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>Votre carte de cr\u00e9dit pr\u00e9sente de nombreux avantages, et pas seulement pour les achats. <\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>S\u00fbre et flexible<\/strong><\/h2>\n\n\n\n<p>Une carte de cr\u00e9dit vous fait b\u00e9n\u00e9ficier d&rsquo;un cr\u00e9dit \u00e0 court terme, que vous payez en r\u00e8gle g\u00e9n\u00e9rale tous les mois. Elle n&rsquo;est pas directement li\u00e9e \u00e0 un compte, ce qui offre <strong>encore plus de s\u00e9curit\u00e9<\/strong>. Avant de payer la facture de la carte de cr\u00e9dit, vous pouvez <strong>v\u00e9rifier les transactions et signaler tout d\u00e9saccord dans les 30 jours.<\/strong><\/p>\n\n\n\n<p>Il peut arriver que vous souhaitiez ponctuellement d\u00e9penser plus que d&rsquo;habitude. Dans ce cas, vous demandez une augmentation temporaire ou permanente de la limite ou convenez avec Viseca d&rsquo;une option de paiement partiel. Le \u00abBuy now, pay later\u00bb est possible depuis longtemps avec votre carte de cr\u00e9dit et vous offre ainsi une <strong>grande flexibilit\u00e9<\/strong> dans le paiement de la facture mensuelle.<\/p>\n\n\n\n<p>Avec de nombreuses cartes de cr\u00e9dit de Viseca, vous participez en outre au <strong>programme de bonus surprize<\/strong>. A chaque paiement, vous collectez des points que vous pouvez \u00e9changer contre des primes ou des bons attrayants dans la boutique de primes ou dont vous pouvez faire don pour une bonne cause.<\/p>\n\n\n\n<figure class=\"wp-block-image size-mid-size\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-1000x562.jpg\" alt=\"\" class=\"wp-image-3327\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-1000x562.jpg 1000w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-300x169.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-1024x576.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-768x432.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-1536x864.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-500x281.jpg 500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512-1500x843.jpg 1500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-KK_vers_16x9_506777512.jpg 1600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\"><em>Surtout en voyage, la couverture d&rsquo;assurance dont vous b\u00e9n\u00e9ficiez avec votre carte de cr\u00e9dit est extr\u00eamement utile. <\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Des assurances pour les voyages, les achats et plus encore<\/strong><\/h2>\n\n\n\n<p>On oublie souvent que la carte de cr\u00e9dit vous fait b\u00e9n\u00e9ficier de <strong>pr\u00e9cieuses assurances<\/strong> qui vous facilitent la vie en cas de sinistre et vous indemnise sans difficult\u00e9s tout au moins du pr\u00e9judice financier. M\u00eame avec une carte Argent\/Classic, vous b\u00e9n\u00e9ficiez d&rsquo;assurances int\u00e9ressantes. Vous en trouverez ici une s\u00e9lection:<\/p>\n\n\n\n\n\t<div class=\"accordion-holder section\">\n\n\t\n\t\t<div id=\"accordion\" class=\"accordion\">\n\t\t\t<div class=\"head\">\n\t\t\t  <h2>Frais de recherche et de sauvetage<\/h2>\n\t\t\t  <i class=\"fas fa-angle-down arrow\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"content\">\n\t\t\t <p>Cette assurance prend en charge les frais de recherche et de sauvetage si vous, en tant que titulaire de la carte, ou votre conjoint(e) ou partenaire de vie vivant dans le m\u00eame foyer ou les enfants \u00e0 charge, \u00eates port\u00e9(s) disparu(s) ou devez \u00eatre sauv\u00e9(s) d&rsquo;une situation d&rsquo;urgence.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\n\t\t<div id=\"accordion\" class=\"accordion\">\n\t\t\t<div class=\"head\">\n\t\t\t  <h2>Assurance annulation de voyage<\/h2>\n\t\t\t  <i class=\"fas fa-angle-down arrow\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"content\">\n\t\t\t <p>Si vous avez pay\u00e9 au moins 60% de votre voyage avec votre carte de cr\u00e9dit et que vous ne pouvez pas partir en raison d&rsquo;un \u00e9v\u00e9nement impr\u00e9vu, les frais d&rsquo;annulation vous seront rembours\u00e9s gr\u00e2ce \u00e0 cette assurance. <\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\n\t\t<div id=\"accordion\" class=\"accordion\">\n\t\t\t<div class=\"head\">\n\t\t\t  <h2>Assurance des frais d&rsquo;interruption de voyage<\/h2>\n\t\t\t  <i class=\"fas fa-angle-down arrow\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"content\">\n\t\t\t <p>Si, au cours de votre voyage, un \u00e9v\u00e9nement se produit, qui n\u00e9cessite d&rsquo;interrompre le voyage, cette assurance prendra en charge la partie non utilis\u00e9e de votre voyage ainsi que les frais suppl\u00e9mentaires pour le voyage de retour et l&rsquo;h\u00e9bergement.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\n\t\t<div id=\"accordion\" class=\"accordion\">\n\t\t\t<div class=\"head\">\n\t\t\t  <h2>Meilleur prix garanti<\/h2>\n\t\t\t  <i class=\"fas fa-angle-down arrow\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"content\">\n\t\t\t <p>Vous avez achet\u00e9 un nouveau t\u00e9l\u00e9viseur et d\u00e9couvert peu de temps apr\u00e8s une meilleure offre pour le m\u00eame appareil. Pas de probl\u00e8me si vous l&rsquo;avez pay\u00e9 avec votre carte de cr\u00e9dit. Dans ce cas, l&rsquo;assurance vous rembourse sans probl\u00e8me la diff\u00e9rence de prix.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\n\t\t<div id=\"accordion\" class=\"accordion\">\n\t\t\t<div class=\"head\">\n\t\t\t  <h2>Prolongation de garantie<\/h2>\n\t\t\t  <i class=\"fas fa-angle-down arrow\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"content\">\n\t\t\t <p>Qu&rsquo;il s&rsquo;agisse d&rsquo;un appareil \u00e9lectrom\u00e9nager ou d&rsquo;un appareil \u00e9lectronique de divertissement ou de communication, si vous l&rsquo;avez pay\u00e9 par carte de cr\u00e9dit, la garantie est prolong\u00e9e de 12 (carte Argent), 24 (carte Or) ou 36 mois (carte Platinum).<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\n\t\t<div id=\"accordion\" class=\"accordion\">\n\t\t\t<div class=\"head\">\n\t\t\t  <h2>Assistance 24 heures sur 24 <\/h2>\n\t\t\t  <i class=\"fas fa-angle-down arrow\"><\/i>\n\t\t\t<\/div>\n\t\t\t<div class=\"content\">\n\t\t\t <p>Gr\u00e2ce \u00e0 cette assurance, une assistance concr\u00e8te est organis\u00e9e en cas d&rsquo;urgence. Il suffit d&rsquo;appeler le +41 44 283 34 18 et des sp\u00e9cialistes vous procureront des adresses de m\u00e9decins, d&rsquo;h\u00f4pitaux et d&rsquo;avocats.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\n\n\n<p><\/p>\n\n\n\n<p>Si vous \u00eates titulaire d&rsquo;une <strong>carte Or ou Platinum<\/strong>, vous b\u00e9n\u00e9ficiez d&rsquo;encore plus d&rsquo;avantages. Cela inclut des assurances telles que <strong>l&rsquo;assurance de franchise pour voitures de location, l&rsquo;assurance bagages, l&rsquo;assurance shopping, l&rsquo;assurance de transport<\/strong> et d&rsquo;autres encore. Retrouvez toutes les <a href=\"https:\/\/www.viseca.ch\/fr\/prestations-des-cartes-de-credit\/assurances\" target=\"_blank\" rel=\"noreferrer noopener\">prestations d&rsquo;assurance en un coup d&rsquo;\u0153il.<\/a><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/card.viseca.ch\/fr\/?cp=12613X06&amp;cs=12614X09&amp;cg=12615X09\" target=\"_blank\" rel=\"noreferrer noopener\">La carte de cr\u00e9dit adapt\u00e9e \u00e0 vos besoins<\/a><\/div>\n<\/div>\n\n\n\n    <div class=\"select-post-holder flex-container section layout-article-teaser\">\n     <div class=\"container\">\n       \n                   \n                 \n     <div class=\"select-post flex-item square\">\n                           \n                                 \n                  <div class=\"featured-image-holder\">\n                     <a href=\"https:\/\/www.mycard.ch\/fr\/demarrez-avec-one\/\">\n                       <div class=\"featured-iamge\">\n                         <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/11\/1_header_vorteil-one_16x9_1832440285-400x400.jpg\" class=\"attachment-mid-size-q size-mid-size-q wp-post-image\" alt=\"\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/11\/1_header_vorteil-one_16x9_1832440285-400x400.jpg 400w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/11\/1_header_vorteil-one_16x9_1832440285-150x150.jpg 150w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/11\/1_header_vorteil-one_16x9_1832440285-200x200.jpg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                       <\/div>\n                     <\/a>\t\n                   <\/div>\n                   \n                   <div class=\"featured-content\">\n                      <a href=\"https:\/\/www.mycard.ch\/fr\/demarrez-avec-one\/\">\n                       <h2>D\u00e9marrez avec one<\/h2>\n                       <span class=\"reading-time\"><span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"2\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. de lecture<\/span>\n                       <\/a>\t\n                  <\/div>\n                     \n                              \n            \n               \n               \n                 \n\n                  <\/div>    \n                      \n                   \n       \n     <\/div> \n   <\/div>  \n","protected":false},"excerpt":{"rendered":"<p>Pendant longtemps, de nombreuses fonctions de la carte de cr\u00e9dit lui \u00e9taient exclusivement r\u00e9serv\u00e9es. A pr\u00e9sent, il existe certes des cartes de paiement, des prestations de service et des produits [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[56],"tags":[],"class_list":["post-3336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paiements-simples"],"acf":{"show_content_below_image":[],"publizieren_auf":["mycard"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les avantages imbattables de votre carte de cr\u00e9dit - MyCard<\/title>\n<meta name=\"description\" content=\"Votre carte de cr\u00e9dit est la carte la plus polyvalente et pr\u00e9sente de nombreux avantages par rapport aux autres. Vous profitez de ces prestations exclusives.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les avantages imbattables de votre carte de cr\u00e9dit - MyCard\" \/>\n<meta property=\"og:description\" content=\"Votre carte de cr\u00e9dit est la carte la plus polyvalente et pr\u00e9sente de nombreux avantages par rapport aux autres. Vous profitez de ces prestations exclusives.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/\" \/>\n<meta property=\"og:site_name\" content=\"MyCard\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-11T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bojan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bojan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/\"},\"author\":{\"name\":\"Bojan\",\"@id\":\"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350\"},\"headline\":\"Les avantages imbattables de votre carte de cr\u00e9dit\",\"datePublished\":\"2023-01-11T06:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/\"},\"wordCount\":690,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg\",\"articleSection\":[\"Paiements simples\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/\",\"url\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/\",\"name\":\"Les avantages imbattables de votre carte de cr\u00e9dit - MyCard\",\"isPartOf\":{\"@id\":\"https:\/\/www.mycard.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg\",\"datePublished\":\"2023-01-11T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350\"},\"description\":\"Votre carte de cr\u00e9dit est la carte la plus polyvalente et pr\u00e9sente de nombreux avantages par rapport aux autres. Vous profitez de ces prestations exclusives.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage\",\"url\":\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg\",\"contentUrl\":\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg\",\"width\":1600,\"height\":900,\"caption\":\"Superhero kid concept. Retro toned image with selective focus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.mycard.ch\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les avantages imbattables de votre carte de cr\u00e9dit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mycard.ch\/#website\",\"url\":\"https:\/\/www.mycard.ch\/\",\"name\":\"MyCard\",\"description\":\"das Kundenmagazin der Viseca Card Services SA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mycard.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350\",\"name\":\"Bojan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mycard.ch\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"caption\":\"Bojan\"},\"url\":\"https:\/\/www.mycard.ch\/fr\/author\/bojan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les avantages imbattables de votre carte de cr\u00e9dit - MyCard","description":"Votre carte de cr\u00e9dit est la carte la plus polyvalente et pr\u00e9sente de nombreux avantages par rapport aux autres. Vous profitez de ces prestations exclusives.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/","og_locale":"fr_FR","og_type":"article","og_title":"Les avantages imbattables de votre carte de cr\u00e9dit - MyCard","og_description":"Votre carte de cr\u00e9dit est la carte la plus polyvalente et pr\u00e9sente de nombreux avantages par rapport aux autres. Vous profitez de ces prestations exclusives.","og_url":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/","og_site_name":"MyCard","article_published_time":"2023-01-11T06:00:00+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg","type":"image\/jpeg"}],"author":"Bojan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Bojan","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#article","isPartOf":{"@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/"},"author":{"name":"Bojan","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"headline":"Les avantages imbattables de votre carte de cr\u00e9dit","datePublished":"2023-01-11T06:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/"},"wordCount":690,"commentCount":0,"image":{"@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg","articleSection":["Paiements simples"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/","url":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/","name":"Les avantages imbattables de votre carte de cr\u00e9dit - MyCard","isPartOf":{"@id":"https:\/\/www.mycard.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage"},"image":{"@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg","datePublished":"2023-01-11T06:00:00+00:00","author":{"@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"description":"Votre carte de cr\u00e9dit est la carte la plus polyvalente et pr\u00e9sente de nombreux avantages par rapport aux autres. Vous profitez de ces prestations exclusives.","breadcrumb":{"@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#primaryimage","url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg","contentUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/12\/vorteil-kk_header_16x9_414605359.jpg","width":1600,"height":900,"caption":"Superhero kid concept. Retro toned image with selective focus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mycard.ch\/die-unschlagbaren-vorteile-ihrer-kreditkarte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mycard.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Les avantages imbattables de votre carte de cr\u00e9dit"}]},{"@type":"WebSite","@id":"https:\/\/www.mycard.ch\/#website","url":"https:\/\/www.mycard.ch\/","name":"MyCard","description":"das Kundenmagazin der Viseca Card Services SA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mycard.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350","name":"Bojan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","caption":"Bojan"},"url":"https:\/\/www.mycard.ch\/fr\/author\/bojan\/"}]}},"wpml_translations":{"de":{"id":"3324","lang":"de","slug":"die-unschlagbaren-vorteile-ihrer-kreditkarte"},"fr":{"id":"3336","lang":"fr","slug":"les-avantages-imbattables-de-votre-carte-de-credit"},"it":{"id":"3341","lang":"it","slug":"i-vantaggi-insuperabili-della-vostra-carta-di-credito"}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:20:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts\/3336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/comments?post=3336"}],"version-history":[{"count":2,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts\/3336\/revisions"}],"predecessor-version":[{"id":3347,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts\/3336\/revisions\/3347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/media\/3337"}],"wp:attachment":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/media?parent=3336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/categories?post=3336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/tags?post=3336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}