{"id":477,"date":"2022-07-12T20:01:00","date_gmt":"2022-07-12T18:01:00","guid":{"rendered":"http:\/\/wordpress.p619856.webspaceconfig.de\/karte-verloren-dank-mobile-payment-schnell-wieder-zahlen\/"},"modified":"2022-10-28T09:54:15","modified_gmt":"2022-10-28T07:54:15","slug":"carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment","status":"publish","type":"post","link":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/","title":{"rendered":"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n\t<div class=\"post-lead-holder\">\n\t\t<div id=\"socialshareprivacy\">\n<p>Les vacances avec la carte de cr\u00e9dit, c&rsquo;est confortable. Aujourd&rsquo;hui, elle permet de payer presque partout. Mais que se passe-t-il si le portemonnaie avec la carte disparait soudainement? Gr\u00e2ce \u00e0 l&rsquo;app one et \u00e0 Mobile Payment, il existe une astuce simple pour utiliser \u00e0 nouveau votre carte de cr\u00e9dit via votre smartphone. Et ce, sans attendre la carte de remplacement.<\/p>\n<\/div>\n\t<\/div>\n\n\n\n\t<div class=\"post-attribute-holder\">\n\t\t<span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"1\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. de lecture-12 juillet 2022 \u2013 \n\t\tFoto: shutterstock\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Au moment de payer au caf\u00e9 de la plage, vous constatez que votre carte de cr\u00e9dit a disparu. Qu&rsquo;elle ait \u00e9t\u00e9 vol\u00e9e, perdue ou simplement \u00e9gar\u00e9e, bloquez-la imm\u00e9diatement. C&rsquo;est le seul moyen de vous assurer que votre carte ne sera pas utilis\u00e9e par des personnes non autoris\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous bloquez la carte via l&rsquo;app one et que vous commandez une carte de remplacement, <strong>vous pouvez \u00e0 nouveau payer d\u00e8s le lendemain avec votre smartphone<\/strong>. Durant la nuit, les donn\u00e9es sont mises \u00e0 jour dans votre compte de carte de cr\u00e9dit ainsi qu&rsquo;aupr\u00e8s de votre fournisseur de Mobile Payment. A l&rsquo;\u00e9tranger, vous devriez attendre trois \u00e0 six jours pour obtenir la carte de remplacement physique. Cela suppose que vous restiez tout ce temps au m\u00eame endroit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Activez Mobile Payment d\u00e8s maintenant et payez aussi en vacances de mani\u00e8re simple et pratique avec votre smartphone. Les instructions suivantes montrent comment configurer Apple Pay sur un iPhone.<\/p>\n\n\n\n\n\n\t<div class=\"blog-slider section singleslider\">\n\t\t<div class=\"container\">\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"blog-slider-holder-single number-nav\" style=\"opacity: 0;\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-blog-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/06\/Screen1_reg-one_fr.jpg\">\n\t\t\t\t\t\t\t<p><div class=\"carousel-inner\" role=\"listbox\">\n<div class=\"item text-center active\">\n<p>Si vous n&rsquo;utilisez pas encore le service num\u00e9rique one, v\u00e9rifiez si votre carte est d\u00e9j\u00e0 enregistr\u00e9e pour le service num\u00e9rique de Viseca. C&rsquo;est la condition essentielle pour pouvoir utiliser Mobile Payment. Vous pouvez enregistrer votre carte via <a href=\"https:\/\/one-digitalservice.ch\/\/register\/login?lang=fr\" target=\"_blank\" rel=\"noopener\">ce lien.<\/a><\/p>\n<\/div>\n<\/div>\n<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-blog-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/Screen2_get-one_all.jpeg\">\n\t\t\t\t\t\t\t<p><div class=\"carousel-inner\" role=\"listbox\">\n<div class=\"item text-center active\">\n<p>Ouvrez l&rsquo;App Store sur votre iPhone. Recherchez l&rsquo;app one et t\u00e9l\u00e9chargez-la. Vous pouvez aussi utiliser <a href=\"https:\/\/apps.apple.com\/ch\/app\/one-control-over-your-cards\/id970439160?l=de\" target=\"_blank\" rel=\"noopener\">ce lien direct.<\/a><\/p>\n<\/div>\n<\/div>\n<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-blog-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/Screen3_one-card_all.jpeg\">\n\t\t\t\t\t\t\t<p><div class=\"carousel-inner\" role=\"listbox\">\n<div class=\"item text-center active\">\n<p>Ouvrez l&rsquo;app one, acc\u00e9dez \u00e0 l&rsquo;onglet \u00abCarte\u00bb et s\u00e9lectionnez \u00abAjouter \u00e0 Apple Wallet\u00bb. Suivez ensuite les instructions.<\/p>\n<\/div>\n<\/div>\n<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"slick-blog-holder\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/Screen4_wallet_all.jpeg\">\n\t\t\t\t\t\t\t<p><div class=\"carousel-inner\" role=\"listbox\">\n<div class=\"item text-center active\">\n<p>C&rsquo;est termin\u00e9! Vous avez d\u00e8s \u00e0 pr\u00e9sent acc\u00e8s \u00e0 Mobile Payment via le Wallet. Lors de votre prochain paiement par carte de cr\u00e9dit, il vous suffit d&rsquo;ouvrir le Wallet, d&rsquo;approcher l&rsquo;appareil du terminal et d&rsquo;attendre quelques instants la confirmation de paiement.<\/p>\n<\/div>\n<\/div>\n<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<section class=\"wp-block-group big-font-red-divider\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les <a href=\"https:\/\/www.viseca.ch\/fr\/service-clientele\/assistance\" target=\"_blank\" rel=\"noreferrer noopener\">FAQ de Viseca<\/a> vous fournissent toutes les informations n\u00e9cessaires pour commander une carte de remplacement.<\/p>\n<\/div><\/section>\n\n\n\n    <div class=\"select-post-holder flex-container section layout-article-teaser\">\n     <div class=\"container\">\n       \n                   \n                 \n     <div class=\"select-post flex-item square\">\n                           \n                                 \n                  <div class=\"featured-image-holder\">\n                     <a href=\"https:\/\/www.mycard.ch\/fr\/plus-de-carte-remplacez-la-en-toute-simplicite\/\">\n                       <div class=\"featured-iamge\">\n                         <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/04\/Header_Karte-weg_neu-400x400.jpg\" class=\"attachment-mid-size-q size-mid-size-q wp-post-image\" alt=\"\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/04\/Header_Karte-weg_neu-400x400.jpg 400w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/04\/Header_Karte-weg_neu-150x150.jpg 150w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/04\/Header_Karte-weg_neu-200x200.jpg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                       <\/div>\n                     <\/a>\t\n                   <\/div>\n                   \n                   <div class=\"featured-content\">\n                      <a href=\"https:\/\/www.mycard.ch\/fr\/plus-de-carte-remplacez-la-en-toute-simplicite\/\">\n                       <h2>Plus de carte? Remplacez-la en toute simplicit\u00e9<\/h2>\n                       <span class=\"reading-time\"><span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"1\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. de lecture<\/span>\n                       <\/a>\t\n                  <\/div>\n                     \n                              \n            \n               \n               \n                 \n\n                  <\/div>    \n                      \n                   \n       \n     <\/div> \n   <\/div>  \n","protected":false},"excerpt":{"rendered":"<p>Au moment de payer au caf\u00e9 de la plage, vous constatez que votre carte de cr\u00e9dit a disparu. Qu&rsquo;elle ait \u00e9t\u00e9 vol\u00e9e, perdue ou simplement \u00e9gar\u00e9e, bloquez-la imm\u00e9diatement. C&rsquo;est le [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[51,56],"tags":[],"class_list":["post-477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-how-to-fr","category-paiements-simples"],"acf":{"show_content_below_image":[],"publizieren_auf":["mycard"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau - MyCard<\/title>\n<meta name=\"description\" content=\"En cas de perte de votre carte de cr\u00e9dit, l&#039;app one et Mobile Payment vous permettent de payer via votre smartphone sans attendre la carte de remplacement.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau - MyCard\" \/>\n<meta property=\"og:description\" content=\"En cas de perte de votre carte de cr\u00e9dit, l&#039;app one et Mobile Payment vous permettent de payer via votre smartphone sans attendre la carte de remplacement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/\" \/>\n<meta property=\"og:site_name\" content=\"MyCard\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-12T18:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-28T07:54:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/07\/Header_portemonnaie-weg_neu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tnt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tnt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/\"},\"author\":{\"name\":\"tnt\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/c6ca71f091957a0ffba4a3c1c432d7f0\"},\"headline\":\"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau\",\"datePublished\":\"2022-07-12T18:01:00+00:00\",\"dateModified\":\"2022-10-28T07:54:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/\"},\"wordCount\":193,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Header_portemonnaie-weg_neu.jpg\",\"articleSection\":[\"Comment faire\",\"Paiements simples\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/\",\"name\":\"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau - MyCard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Header_portemonnaie-weg_neu.jpg\",\"datePublished\":\"2022-07-12T18:01:00+00:00\",\"dateModified\":\"2022-10-28T07:54:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/c6ca71f091957a0ffba4a3c1c432d7f0\"},\"description\":\"En cas de perte de votre carte de cr\u00e9dit, l'app one et Mobile Payment vous permettent de payer via votre smartphone sans attendre la carte de remplacement.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Header_portemonnaie-weg_neu.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Header_portemonnaie-weg_neu.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/\",\"name\":\"MyCard\",\"description\":\"das Kundenmagazin der Viseca Card Services SA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mycard.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/c6ca71f091957a0ffba4a3c1c432d7f0\",\"name\":\"tnt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee0dc93fb8259abeed5760aeac2c8b3dc3b7fc69388c34acdf5ca8a4b2429e43?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee0dc93fb8259abeed5760aeac2c8b3dc3b7fc69388c34acdf5ca8a4b2429e43?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ee0dc93fb8259abeed5760aeac2c8b3dc3b7fc69388c34acdf5ca8a4b2429e43?s=96&d=mm&r=g\",\"caption\":\"tnt\"},\"url\":\"https:\\\/\\\/www.mycard.ch\\\/fr\\\/author\\\/tnt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau - MyCard","description":"En cas de perte de votre carte de cr\u00e9dit, l'app one et Mobile Payment vous permettent de payer via votre smartphone sans attendre la carte de remplacement.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/","og_locale":"fr_FR","og_type":"article","og_title":"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau - MyCard","og_description":"En cas de perte de votre carte de cr\u00e9dit, l'app one et Mobile Payment vous permettent de payer via votre smartphone sans attendre la carte de remplacement.","og_url":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/","og_site_name":"MyCard","article_published_time":"2022-07-12T18:01:00+00:00","article_modified_time":"2022-10-28T07:54:15+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/07\/Header_portemonnaie-weg_neu.jpg","type":"image\/jpeg"}],"author":"tnt","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"tnt","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#article","isPartOf":{"@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/"},"author":{"name":"tnt","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/c6ca71f091957a0ffba4a3c1c432d7f0"},"headline":"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau","datePublished":"2022-07-12T18:01:00+00:00","dateModified":"2022-10-28T07:54:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/"},"wordCount":193,"commentCount":0,"image":{"@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/07\/Header_portemonnaie-weg_neu.jpg","articleSection":["Comment faire","Paiements simples"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/","url":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/","name":"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau - MyCard","isPartOf":{"@id":"https:\/\/www.mycard.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#primaryimage"},"image":{"@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/07\/Header_portemonnaie-weg_neu.jpg","datePublished":"2022-07-12T18:01:00+00:00","dateModified":"2022-10-28T07:54:15+00:00","author":{"@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/c6ca71f091957a0ffba4a3c1c432d7f0"},"description":"En cas de perte de votre carte de cr\u00e9dit, l'app one et Mobile Payment vous permettent de payer via votre smartphone sans attendre la carte de remplacement.","breadcrumb":{"@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#primaryimage","url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/07\/Header_portemonnaie-weg_neu.jpg","contentUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/07\/Header_portemonnaie-weg_neu.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.mycard.ch\/fr\/carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mycard.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Portemonnaie perdue? Ainsi, vous payez rapidement \u00e0 nouveau"}]},{"@type":"WebSite","@id":"https:\/\/www.mycard.ch\/#website","url":"https:\/\/www.mycard.ch\/","name":"MyCard","description":"das Kundenmagazin der Viseca Card Services SA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mycard.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/c6ca71f091957a0ffba4a3c1c432d7f0","name":"tnt","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ee0dc93fb8259abeed5760aeac2c8b3dc3b7fc69388c34acdf5ca8a4b2429e43?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ee0dc93fb8259abeed5760aeac2c8b3dc3b7fc69388c34acdf5ca8a4b2429e43?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ee0dc93fb8259abeed5760aeac2c8b3dc3b7fc69388c34acdf5ca8a4b2429e43?s=96&d=mm&r=g","caption":"tnt"},"url":"https:\/\/www.mycard.ch\/fr\/author\/tnt\/"}]}},"wpml_translations":{"de":{"id":"193","lang":"de","slug":"karte-verloren-dank-mobile-payment-schnell-wieder-zahlen"},"it":{"id":"476","lang":"it","slug":"carta-smarrita-con-mobile-payment-potete-velocemente-tornare-a-effettuare-i-vostri-pagamenti"},"fr":{"id":"477","lang":"fr","slug":"carte-perdue-payez-a-nouveau-rapidement-grace-a-mobile-payment"}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 10:16:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":28,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"predecessor-version":[{"id":3009,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/posts\/477\/revisions\/3009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/media\/2268"}],"wp:attachment":[{"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mycard.ch\/fr\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}