{"id":1838,"date":"2022-08-17T16:43:28","date_gmt":"2022-08-17T14:43:28","guid":{"rendered":"http:\/\/xbgnygylyr.cyon.link\/non-esistono-richieste-banali\/"},"modified":"2022-10-28T10:08:11","modified_gmt":"2022-10-28T08:08:11","slug":"non-esistono-richieste-banali","status":"publish","type":"post","link":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/","title":{"rendered":"\u00abNon esistono richieste banali\u00bb"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n\t<div class=\"post-lead-holder\">\n\t\t<p>Danilo Montanari \u00e8 un collaboratore della Customer Communication di Viseca e ogni giorno arriva a rispondere a 60 richieste di clienti in quattro lingue, sempre individualmente e con l&#8217;obiettivo di aiutare ogni cliente fornendo la risposta giusta. <\/p>\n\t<\/div>\n\n\n\n\t<div class=\"post-attribute-holder\">\n\t\t<span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"3\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. di lettura-17 Agosto 2022 \u2013 \n\t\tFotos: Dani Winkler\t<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Customer Communication di Viseca risponde a tutte le richieste scritte dei clienti pervenute per e-mail o posta. Da tre anni Danilo Montanari \u00e8 impegnato a rispondere alle pi\u00f9 disparate richieste dei clienti in quattro lingue, per lo pi\u00f9 per iscritto, ma di tanto in tanto anche telefonicamente. \u00abMi piace aiutare gli altri, parlare e scrivere\u00bb, afferma il collaboratore proveniente da un altro percorso professionale e che ha una perfetta padronanza, sia scritta che orale, della lingua tedesca, italiana, francese e inglese. \u00c8 cresciuto a Genova, ha iniziato a studiare filosofia in Italia, poi ha svolto un semestre in Germania e ha completato il suo percorso in Svizzera. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_02_052_1600x1000-1024x640.jpg\" alt=\"\" class=\"wp-image-1825\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_02_052_1600x1000-1024x640.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_02_052_1600x1000-300x188.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_02_052_1600x1000-768x480.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_02_052_1600x1000-1536x960.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_02_052_1600x1000.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un investigatore poliglotta <\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Non esistono richieste e tanto meno risposte banali:  ogni giorno Danilo arriva a rispondere a 60 e-mail che riguardano transazioni, contenuti delle fatture o il mancato funzionamento delle carte. I reclami pervengono pi\u00f9 frequentemente per posta e, se si tratta di un caso complesso, ci pu\u00f2 volere un&#8217;intera giornata di lavoro per risolverlo. Pertanto, talvolta capita che le risposte tardino ad arrivare, sebbene si cerchi di rispondere a ogni richiesta il pi\u00f9 rapidamente possibile.  L&#8217;importante, per Danilo, \u00e8 fornire una risposta individuale: la qualit\u00e0 viene prima della quantit\u00e0. Il cliente non deve avere la sensazione di ricevere la risposta da un bot. All&#8217;inizio, infatti, Danilo \u00e8 stato scambiato per un programma di questo genere. \u00abHo telefonato subito al cliente in questione per dimostrargli che ero una persona in carne e ossa\u00bb, cos\u00ec Danilo riassume la sua esperienza pi\u00f9 divertente e allo stesso tempo pi\u00f9 memorabile. Per ogni richiesta \u00e8 fondamentale chiarire i fatti con precisione, per fornire poi la risposta giusta. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_03_040_1600x1000-1024x640.jpg\" alt=\"\" class=\"wp-image-1826\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_03_040_1600x1000-1024x640.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_03_040_1600x1000-300x188.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_03_040_1600x1000-768x480.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_03_040_1600x1000-1536x960.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_03_040_1600x1000.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pi\u00f9 di 10 anni fa, Danilo si \u00e8 candidato per un posto di lavoro nel call center di Viseca, dove \u00e8 rimasto pi\u00f9 a lungo del previsto. Poi ha colto l&#8217;occasione di passare a un altro team e, successivamente, di entrare nella Customer Communication. Gli piace lavorare a contatto con i clienti e collaborare con i colleghi del team. Comunicare in pi\u00f9 lingue \u00e8 per lui tanto motivante quanto affrontare casi speciali di cui si occupa continuamente. \u00abSvolgo un lavoro molto creativo per essere in un ambito commerciale\u00bb, spiega Danilo, \u00aba volte assomiglia a un gioco investigativo in cui devo capire, per esempio, quale intrigo si nasconde dietro a una transazione\u00bb. <\/p>\n\n\n\n    <div class=\"select-post-holder flex-container section layout-article-teaser\">\n     <div class=\"container\">\n       \n                   \n                        \n                   \n       \n     <\/div> \n   <\/div>  \n\n\n\n<h2 class=\"wp-block-heading\"><strong>Spesso basta una telefonata<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Molte richieste riguardano le commissioni relative alle transazioni che, come spiega Danilo, di solito sono quelle che si risolvono pi\u00f9 velocemente. La situazione si fa pi\u00f9 complicata se l&#8217;esercente a cui la transazione \u00e8 collegata non \u00e8 immediatamente riconoscibile. Chi controlla regolarmente le proprie transazioni in one, \u00e8 anche in grado di riconoscerle nella maggior parte dei casi. A differenza del cliente, Danilo vede se il pagamento \u00e8 stato effettuato online o in negozio. Poich\u00e9 i dati relativi alle transazioni non possono essere comunicati per e-mail, in questi casi Danilo prende in mano il telefono e, insieme al cliente, individua l&#8217;origine della transazione. Il giorno della settimana in cui l&#8217;operazione \u00e8 stata effettuata o qualsiasi altra informazione in merito possono essere di aiuto tanto quanto la lunga esperienza del collaboratore.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_04_069_1600x1000-1024x640.jpg\" alt=\"\" class=\"wp-image-1827\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_04_069_1600x1000-1024x640.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_04_069_1600x1000-300x188.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_04_069_1600x1000-768x480.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_04_069_1600x1000-1536x960.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_04_069_1600x1000.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Oltre a far parte della sua vita professionale, le lingue sono anche un hobby per Danilo. Insieme alla moglie e alla figlia di quattro anni parla di tanto in tanto un po&#8217; di polacco per cercare di migliorare costantemente le sue conoscenze. Il tempo libero \u00e8 dedicato principalmente alla figlia, che lo tiene lontano dalla sua amata Vespa. Durante le vacanze e nei fine settimana gli piace viaggiare in camper insieme alla moglie e alla figlia alla scoperta di luoghi interessanti. Essendo italiano, \u00e8 un uomo di famiglia e un fan del Genoa FC. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_05_031_1600x1000-1024x640.jpg\" alt=\"\" class=\"wp-image-1828\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_05_031_1600x1000-1024x640.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_05_031_1600x1000-300x188.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_05_031_1600x1000-768x480.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_05_031_1600x1000-1536x960.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_05_031_1600x1000.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Think before you click!<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Gli amici e i colleghi descrivono Danilo come una persona estremamente disponibile e affidabile. Il suo modo di porsi in maniera discreta e, al tempo stesso, aperta e comunicativa gli \u00e8 sempre di grande aiuto nell&#8217;affrontare le molteplici richieste dei clienti. Quando fornisce un consiglio a un cliente, non manca mai di aggiungerne subito un altro, ovvero \u00abThink before you click!\u00bb Le raccomandazioni sulla cautela da usare nel trattamento dei dati personali, soprattutto quando ci sono di mezzo le carte di credito, non sono mai abbastanza. Altrettanto importante \u00e8 controllare regolarmente le transazioni tramite l&#8217;app one: \u00abMolti clienti non lo fanno\u00bb, afferma Danilo, \u00abma verificare la fattura non solo \u00e8 d&#8217;obbligo, ma aiuta anche a riconoscere tempestivamente le transazioni abusive e rende la carta di credito ancora pi\u00f9 sicura.\u00bb <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_06_018_1600x1000-1024x640.jpg\" alt=\"\" class=\"wp-image-1829\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_06_018_1600x1000-1024x640.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_06_018_1600x1000-300x188.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_06_018_1600x1000-768x480.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_06_018_1600x1000-1536x960.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_06_018_1600x1000.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Danilo capita regolarmente di ricevere complimenti per il suo operato e la sua disponibilit\u00e0 direttamente dai clienti. Occasionalmente riceve feedback anche dai suoi superiori, ai quali i clienti rivolgono il loro ringraziamento. Questi riscontri gli fanno molto piacere e sono la conferma che svolge il suo lavoro nel modo giusto. In queste occasioni, pensa tra s\u00e9 e s\u00e9: \u00abWow, you made my day!\u00bb<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.viseca.ch\/it\/servizio-clienti\/contatto\" target=\"_blank\" rel=\"noreferrer noopener\">Il vostro contatto diretto con Viseca <\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Customer Communication di Viseca risponde a tutte le richieste scritte dei clienti pervenute per e-mail o posta. Da tre anni Danilo Montanari \u00e8 impegnato a rispondere alle pi\u00f9 disparate [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[58],"tags":[],"class_list":["post-1838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuove-scoperte"],"acf":{"show_content_below_image":[],"publizieren_auf":["mycard"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abNon esistono richieste banali\u00bb - MyCard<\/title>\n<meta name=\"description\" content=\"Danilo Montanari lavora per la Customer Communication di Viseca. Ogni giorno arriva a rispondere individualmente a 60 richieste di clienti e in 4 lingue.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abNon esistono richieste banali\u00bb - MyCard\" \/>\n<meta property=\"og:description\" content=\"Danilo Montanari lavora per la Customer Communication di Viseca. Ogni giorno arriva a rispondere individualmente a 60 richieste di clienti e in 4 lingue.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/\" \/>\n<meta property=\"og:site_name\" content=\"MyCard\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-17T14:43:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-28T08:08:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_01_064_1600x1000_header-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bojan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bojan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/\"},\"author\":{\"name\":\"Bojan\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\"},\"headline\":\"\u00abNon esistono richieste banali\u00bb\",\"datePublished\":\"2022-08-17T14:43:28+00:00\",\"dateModified\":\"2022-10-28T08:08:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/\"},\"wordCount\":808,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/VISE_Danilo_01_064_1600x1000_header-2.jpg\",\"articleSection\":[\"Nuove scoperte\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/\",\"name\":\"\u00abNon esistono richieste banali\u00bb - MyCard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/VISE_Danilo_01_064_1600x1000_header-2.jpg\",\"datePublished\":\"2022-08-17T14:43:28+00:00\",\"dateModified\":\"2022-10-28T08:08:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\"},\"description\":\"Danilo Montanari lavora per la Customer Communication di Viseca. Ogni giorno arriva a rispondere individualmente a 60 richieste di clienti e in 4 lingue.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/VISE_Danilo_01_064_1600x1000_header-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/VISE_Danilo_01_064_1600x1000_header-2.jpg\",\"width\":1600,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/non-esistono-richieste-banali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abNon esistono richieste banali\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/\",\"name\":\"MyCard\",\"description\":\"das Kundenmagazin der Viseca Card Services SA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mycard.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\",\"name\":\"Bojan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"caption\":\"Bojan\"},\"url\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/author\\\/bojan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abNon esistono richieste banali\u00bb - MyCard","description":"Danilo Montanari lavora per la Customer Communication di Viseca. Ogni giorno arriva a rispondere individualmente a 60 richieste di clienti e in 4 lingue.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/","og_locale":"it_IT","og_type":"article","og_title":"\u00abNon esistono richieste banali\u00bb - MyCard","og_description":"Danilo Montanari lavora per la Customer Communication di Viseca. Ogni giorno arriva a rispondere individualmente a 60 richieste di clienti e in 4 lingue.","og_url":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/","og_site_name":"MyCard","article_published_time":"2022-08-17T14:43:28+00:00","article_modified_time":"2022-10-28T08:08:11+00:00","og_image":[{"width":1600,"height":1000,"url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_01_064_1600x1000_header-2.jpg","type":"image\/jpeg"}],"author":"Bojan","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Bojan","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#article","isPartOf":{"@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/"},"author":{"name":"Bojan","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"headline":"\u00abNon esistono richieste banali\u00bb","datePublished":"2022-08-17T14:43:28+00:00","dateModified":"2022-10-28T08:08:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/"},"wordCount":808,"commentCount":0,"image":{"@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_01_064_1600x1000_header-2.jpg","articleSection":["Nuove scoperte"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/","url":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/","name":"\u00abNon esistono richieste banali\u00bb - MyCard","isPartOf":{"@id":"https:\/\/www.mycard.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#primaryimage"},"image":{"@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_01_064_1600x1000_header-2.jpg","datePublished":"2022-08-17T14:43:28+00:00","dateModified":"2022-10-28T08:08:11+00:00","author":{"@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"description":"Danilo Montanari lavora per la Customer Communication di Viseca. Ogni giorno arriva a rispondere individualmente a 60 richieste di clienti e in 4 lingue.","breadcrumb":{"@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#primaryimage","url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_01_064_1600x1000_header-2.jpg","contentUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2022\/08\/VISE_Danilo_01_064_1600x1000_header-2.jpg","width":1600,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.mycard.ch\/it\/non-esistono-richieste-banali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mycard.ch\/it\/"},{"@type":"ListItem","position":2,"name":"\u00abNon esistono richieste banali\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.mycard.ch\/#website","url":"https:\/\/www.mycard.ch\/","name":"MyCard","description":"das Kundenmagazin der Viseca Card Services SA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mycard.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350","name":"Bojan","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","caption":"Bojan"},"url":"https:\/\/www.mycard.ch\/it\/author\/bojan\/"}]}},"wpml_translations":{"de":{"id":"1823","lang":"de","slug":"nullachtfuenfzehn-gibt-es-nicht"},"fr":{"id":"1832","lang":"fr","slug":"il-ny-a-pas-de-reponse-banale"},"it":{"id":"1838","lang":"it","slug":"non-esistono-richieste-banali"}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 05:35:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/1838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/comments?post=1838"}],"version-history":[{"count":9,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/1838\/revisions"}],"predecessor-version":[{"id":3030,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/1838\/revisions\/3030"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/media\/1840"}],"wp:attachment":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/media?parent=1838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/categories?post=1838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/tags?post=1838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}