{"id":6882,"date":"2025-09-10T00:01:00","date_gmt":"2025-09-09T22:01:00","guid":{"rendered":"https:\/\/www.mycard.ch\/?p=6882"},"modified":"2025-12-16T17:38:18","modified_gmt":"2025-12-16T16:38:18","slug":"cosi-evitate-di-cadere-nella-trappola-del-phishing","status":"publish","type":"post","link":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/","title":{"rendered":"Cos\u00ec evitate di cadere nella trappola del phishing"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n\t<div class=\"post-lead-holder\">\n\t\t<p>Il phishing pu\u00f2 ingannare chiunque! Per questo motivo \u00e8 importante avere sempre presenti le principali regole di comportamento. Informatevi periodicamente sulle tendenze attuali, p. es. sulla piattaforma Card Security. Mettete alla prova le vostre conoscenze!<\/p>\n\t<\/div>\n\n\n\n\t<div class=\"post-attribute-holder\">\n\t\t<span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"2\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. di lettura-10 Settembre 2025 \u2013 \n\t\tFoto: shutterstock \/ Card Security\t<\/div>\n\n\n\n<div class=\"wp-block-group grey box has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>In breve<\/strong><\/h2>\n\n\n\n<ul style=\"background-color:#f7f7f7\" class=\"wp-block-list has-background\">\n<li>Il phishing pu\u00f2 ingannare chiunque se tempi e contenuti coincidono perfettamente.<\/li>\n\n\n\n<li>Sei regole di comportamento aiutano a non cadere nella trappola del phishing.&nbsp;<\/li>\n\n\n\n<li>Card Security \u00e8 la piattaforma che sensibilizza all&#8217;uso sicuro delle carte e alla cybercriminalit\u00e0.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Gli attacchi di phishing non solo aumentano, ma sono anche sempre pi\u00f9 subdoli. Se inviato al momento \u201cgiusto\u201d, con contenuti apparentemente autentici e costruiti per mettere fretta, un attacco di phishing oggi pu\u00f2 colpire chiunque. Grazie all&#8217;uso dell&#8217;intelligenza artificiale e alle capacit\u00e0 organizzative della criminalit\u00e0, il phishing ha raggiunto oggi un livello di \u201cprofessionalit\u00e0\u201d tale da rendere <strong>sempre pi\u00f9 difficile distinguere, a colpo d&#8217;occhio, il vero dal falso.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con il cosiddetto <strong>social engineering<\/strong>, i criminali raccolgono dai social network e dal web informazioni mirate sulle loro vittime e possono quindi contattarle in modo personale e ancora pi\u00f9 credibile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La buona notizia: ci sono <strong>semplici regole di comportamento<\/strong> che vi proteggono in modo affidabile dal phishing \u2013 indipendentemente dal fatto che avvenga per e-mail, SMS o telefono.<\/p>\n\n\n\n<div class=\"wp-block-group grey box has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Regole di comportamento<\/h2>\n\n\n\n<ol style=\"background-color:#f7f7f7\" class=\"wp-block-list has-background\">\n<li><strong>Non aprite e-mail, SMS o messaggi da mittenti sconosciuti o con contenuti sospetti e ignorate le chiamate di sconosciuti.<\/strong><\/li>\n\n\n\n<li>Quando vi <strong>si mette fretta, si minaccia il blocco del conto o si esercita qualsiasi altro tipo di pressione<\/strong>, si tratta di un tentativo di frode. Eliminate l&#8217;e-mail o terminate la chiamata immediatamente.<\/li>\n\n\n\n<li>Se non siete sicuri, <strong>contattate direttamente l&#8217;azienda o la persona in questione<\/strong> tramite i canali ufficiali (servizio clienti, app one, numero di telefono personale).<\/li>\n\n\n\n<li>Occorre prestare particolare attenzione ai <strong>codici QR<\/strong>. Analizzate attentamente il link nella modalit\u00e0 anteprima e assicuratevi di essere sul sito giusto.<\/li>\n\n\n\n<li>E non cliccate i <strong>link all&#8217;interno di un&#8217;e-mail<\/strong>, a meno che non vi fidiate al 100%.<\/li>\n\n\n\n<li><strong>Non condividete mai password, informazioni sul conto o sulla carta di credito e codici SMS.<\/strong><\/li>\n<\/ol>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Card Security<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La piattaforma di prevenzione Card Security informa sulle truffe che coinvolgono le carta di credito e di debito. Su card-security.ch troverete informazioni utili e approfondite sull&#8217;uso della vostra carta, sull&#8217;attuale abuso della carta e su come proteggervi da questi abusi.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-1024x576.jpg\" alt=\"\" class=\"wp-image-6884\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-1024x576.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-300x169.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-768x432.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-1536x864.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-1000x562.jpg 1000w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-500x281.jpg 500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT-1500x843.jpg 1500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/02_phisherin_auswahl_1600x900_IT.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La campagna attuale pone l&#8217;accento sui rischi del phishing in diversi canali e comprende anche \u00abLINDA lo sgama!\u00bb: oltre ad attirare l&#8217;attenzione, la pescatrice rappresenta anche una checklist che vi aiuta a riconoscere le truffe ancora pi\u00f9 rapidamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Informatevi ora sul <a href=\"https:\/\/www.card-security.ch\/it\/\">sito di Card Security <\/a>e mettete alla prova le vostre conoscenze in materia di phishing e abuso di carte. <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.card-security.ch\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><strong>All&#8217;attuale campagna di Card Security!<\/strong><\/strong><\/a><\/div>\n<\/div>\n\n\n\n    <div class=\"select-post-holder flex-container section layout-article-teaser\">\n     <div class=\"container\">\n       \n                   \n                 \n     <div class=\"select-post flex-item square\">\n                           \n                                 \n                  <div class=\"featured-image-holder\">\n                     <a href=\"https:\/\/www.mycard.ch\/it\/card-security-la-piattaforma-per-la-sicurezza-della-carta\/\">\n                       <div class=\"featured-iamge\">\n                         <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/05\/KSI_Kampagne_LINDA_Viseca_Titelbild_1600x900_it-400x400.jpg\" class=\"attachment-mid-size-q size-mid-size-q wp-post-image\" alt=\"\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/05\/KSI_Kampagne_LINDA_Viseca_Titelbild_1600x900_it-400x400.jpg 400w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/05\/KSI_Kampagne_LINDA_Viseca_Titelbild_1600x900_it-150x150.jpg 150w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/05\/KSI_Kampagne_LINDA_Viseca_Titelbild_1600x900_it-200x200.jpg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                       <\/div>\n                     <\/a>\t\n                   <\/div>\n                   \n                   <div class=\"featured-content\">\n                      <a href=\"https:\/\/www.mycard.ch\/it\/card-security-la-piattaforma-per-la-sicurezza-della-carta\/\">\n                       <h2>Card Security: la piattaforma per la sicurezza della carta<\/h2>\n                       <span class=\"reading-time\"><span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"3\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. di lettura<\/span>\n                       <\/a>\t\n                  <\/div>\n                     \n                              \n            \n               \n               \n                 \n\n                  <\/div>    \n                      \n                   \n       \n     <\/div> \n   <\/div>  \n","protected":false},"excerpt":{"rendered":"<p>In breve Gli attacchi di phishing non solo aumentano, ma sono anche sempre pi\u00f9 subdoli. Se inviato al momento \u201cgiusto\u201d, con contenuti apparentemente autentici e costruiti per mettere fretta, un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-6882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maggiore-sicurezza"],"acf":{"show_content_below_image":[],"publizieren_auf":["mycard"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cos\u00ec evitate di cadere nella trappola del phishing - MyCard<\/title>\n<meta name=\"description\" content=\"Il phishing pu\u00f2 ingannare chiunque! Per questo dovreste sempre tenervi informati e avere presenti le regole di comportamento, p. es. tramite card-security.ch.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cos\u00ec evitate di cadere nella trappola del phishing - MyCard\" \/>\n<meta property=\"og:description\" content=\"Il phishing pu\u00f2 ingannare chiunque! Per questo dovreste sempre tenervi informati e avere presenti le regole di comportamento, p. es. tramite card-security.ch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/\" \/>\n<meta property=\"og:site_name\" content=\"MyCard\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-09T22:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T16:38:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bojan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bojan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/\"},\"author\":{\"name\":\"Bojan\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\"},\"headline\":\"Cos\u00ec evitate di cadere nella trappola del phishing\",\"datePublished\":\"2025-09-09T22:01:00+00:00\",\"dateModified\":\"2025-12-16T16:38:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/\"},\"wordCount\":423,\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/01_header_phishing_SB9_16x9_1759435418-1.jpg\",\"articleSection\":[\"Maggiore sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/\",\"name\":\"Cos\u00ec evitate di cadere nella trappola del phishing - MyCard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/01_header_phishing_SB9_16x9_1759435418-1.jpg\",\"datePublished\":\"2025-09-09T22:01:00+00:00\",\"dateModified\":\"2025-12-16T16:38:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\"},\"description\":\"Il phishing pu\u00f2 ingannare chiunque! Per questo dovreste sempre tenervi informati e avere presenti le regole di comportamento, p. es. tramite card-security.ch.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/01_header_phishing_SB9_16x9_1759435418-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/01_header_phishing_SB9_16x9_1759435418-1.jpg\",\"width\":1600,\"height\":900,\"caption\":\"Trouts fishing with coopnet. Fish caught into a fishing net.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/cosi-evitate-di-cadere-nella-trappola-del-phishing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cos\u00ec evitate di cadere nella trappola del phishing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/\",\"name\":\"MyCard\",\"description\":\"das Kundenmagazin der Viseca Card Services SA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mycard.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\",\"name\":\"Bojan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"caption\":\"Bojan\"},\"url\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/author\\\/bojan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cos\u00ec evitate di cadere nella trappola del phishing - MyCard","description":"Il phishing pu\u00f2 ingannare chiunque! Per questo dovreste sempre tenervi informati e avere presenti le regole di comportamento, p. es. tramite card-security.ch.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/","og_locale":"it_IT","og_type":"article","og_title":"Cos\u00ec evitate di cadere nella trappola del phishing - MyCard","og_description":"Il phishing pu\u00f2 ingannare chiunque! Per questo dovreste sempre tenervi informati e avere presenti le regole di comportamento, p. es. tramite card-security.ch.","og_url":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/","og_site_name":"MyCard","article_published_time":"2025-09-09T22:01:00+00:00","article_modified_time":"2025-12-16T16:38:18+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1.jpg","type":"image\/jpeg"}],"author":"Bojan","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Bojan","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/#article","isPartOf":{"@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/"},"author":{"name":"Bojan","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"headline":"Cos\u00ec evitate di cadere nella trappola del phishing","datePublished":"2025-09-09T22:01:00+00:00","dateModified":"2025-12-16T16:38:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/"},"wordCount":423,"image":{"@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1.jpg","articleSection":["Maggiore sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/","url":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/","name":"Cos\u00ec evitate di cadere nella trappola del phishing - MyCard","isPartOf":{"@id":"https:\/\/www.mycard.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/#primaryimage"},"image":{"@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1.jpg","datePublished":"2025-09-09T22:01:00+00:00","dateModified":"2025-12-16T16:38:18+00:00","author":{"@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"description":"Il phishing pu\u00f2 ingannare chiunque! Per questo dovreste sempre tenervi informati e avere presenti le regole di comportamento, p. es. tramite card-security.ch.","breadcrumb":{"@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/#primaryimage","url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1.jpg","contentUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1.jpg","width":1600,"height":900,"caption":"Trouts fishing with coopnet. Fish caught into a fishing net."},{"@type":"BreadcrumbList","@id":"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mycard.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Cos\u00ec evitate di cadere nella trappola del phishing"}]},{"@type":"WebSite","@id":"https:\/\/www.mycard.ch\/#website","url":"https:\/\/www.mycard.ch\/","name":"MyCard","description":"das Kundenmagazin der Viseca Card Services SA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mycard.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350","name":"Bojan","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","caption":"Bojan"},"url":"https:\/\/www.mycard.ch\/it\/author\/bojan\/"}]}},"wpml_translations":{"de":{"id":"6870","lang":"de","slug":"so-tappen-sie-nicht-in-die-phishing-falle"},"fr":{"id":"6876","lang":"fr","slug":"ne-tombez-plus-dans-le-piege-du-phishing"},"it":{"id":"6882","lang":"it","slug":"cosi-evitate-di-cadere-nella-trappola-del-phishing"}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:14:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/6882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/comments?post=6882"}],"version-history":[{"count":4,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/6882\/revisions"}],"predecessor-version":[{"id":7162,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/6882\/revisions\/7162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/media\/6883"}],"wp:attachment":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/media?parent=6882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/categories?post=6882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/tags?post=6882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}