{"id":7770,"date":"2026-04-01T00:01:00","date_gmt":"2026-03-31T22:01:00","guid":{"rendered":"https:\/\/www.mycard.ch\/?p=7770"},"modified":"2026-03-23T15:28:51","modified_gmt":"2026-03-23T14:28:51","slug":"voci-clonate-volti-falsificati-come-proteggersi-dalle-frodi-basate-sull-ia","status":"publish","type":"post","link":"https:\/\/www.mycard.ch\/it\/voci-clonate-volti-falsificati-come-proteggersi-dalle-frodi-basate-sull-ia\/","title":{"rendered":"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div>\n\t<div class=\"post-lead-holder\">\n\t\t<p>Squilla il telefono, la voce vi sembra familiare: vostro padre, il vostro capo, il vostro socio in affari. E se quella voce non fosse reale? Con l\u2019intelligenza artificiale (IA), i truffatori sono in grado di clonare le voci in pochi secondi, e persino di effettuare videochiamate con volti falsificati. Siate particolarmente prudenti, quindi, se ricevete chiamate da numeri sconosciuti. L\u2019ultima trovata? Le telefonate mute, per farvi parlare al fine di registrare la vostra voce e utilizzarla a scopi fraudolenti.<\/p>\n\t<\/div>\n\n\n\n\t<div class=\"post-attribute-holder\">\n\t\t<span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"3\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. di lettura-1 Aprile 2026 \u2013 \n\t\tFoto: shutterstock\t<\/div>\n\n\n\n<div class=\"wp-block-group grey box has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\">In breve<\/h2>\n\n\n\n<ul style=\"background-color:#f7f7f7\" class=\"wp-block-list has-background\">\n<li>I truffatori clonano le voci con l\u2019IA: bastano 10-20 secondi di materiale audio.<\/li>\n\n\n\n<li>Le telefonate mute e le videochiamate da mittenti sconosciuti hanno lo scopo di raccogliere materiale audio e video per successive truffe.<\/li>\n\n\n\n<li>La forma di tutela migliore: mantenete la calma, richiamate al numero che conoscete.<\/li>\n\n\n\n<li>In caso di transazioni sospette, Viseca vi contatta esclusivamente tramite l\u2019app one o invitandovi a mettervi in comunicazione con il servizio clienti.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-1024x576.jpg\" alt=\"\" class=\"wp-image-7764\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-1024x576.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-300x169.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-768x432.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-1536x864.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-1000x562.jpg 1000w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-500x281.jpg 500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900-1500x843.jpg 1500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_1_2671316119_1600x900.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>In Svizzera, solo nel 2025, sono state effettuate truffe telefoniche per circa 250 milioni di CHF.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il telefono squilla. Rispondete: silenzio. Istintivamente dite: \u00abPronto? Chi parla?\u00bb E siete in trappola. I truffatori si servono delle <strong>telefonate mute proprio per raccogliere campioni vocali<\/strong>. A un sistema di IA bastano 10-20 secondi della vostra voce \u2013 tonalit\u00e0, ritmo dell\u2019eloquio, accento \u2013 per generare una copia quasi indistinguibile dall\u2019originale. Lo stesso vale per le <strong>videochiamate, che vengono utilizzate per creare deepfake.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Voci e volti falsificati <\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le voci clonate vengono impiegate, ad esempio, nella cosiddetta <strong>\u00abtruffa del falso nipote 2.0\u00bb<\/strong>: ricevete una chiamata da vostro nipote che sembra essere in difficolt\u00e0 e ha urgente bisogno di soldi. La pressione emotiva \u00e8 enorme, e chi \u00e8 preso dal panico non fa domande.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-1024x576.jpg\" alt=\"\" class=\"wp-image-7765\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-1024x576.jpg 1024w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-300x169.jpg 300w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-768x432.jpg 768w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-1536x864.jpg 1536w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-1000x562.jpg 1000w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-500x281.jpg 500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900-1500x843.jpg 1500w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_2_2283408095_1600x900.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Quando una voce familiare improvvisamente vi chiede dei soldi, mantenere la calma e mettere in dubbio quanto vi viene detto \u00e8 il modo migliore per tutelarvi.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">I <strong>video deepfake<\/strong> sono una forma di truffa ancora pi\u00f9 evoluta: si tratta di registrazioni manipolate in cui persone reali dicono o fanno cose che in realt\u00e0 non sono mai accadute. In Svizzera sono stati posti in circolazione video falsi con la Consigliera federale Keller-Sutter e la presentatrice della SRF Mona Vetsch che pubblicizzavano piattaforme di investimento fraudolente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un recente <a href=\"https:\/\/www.srf.ch\/sendungen\/kassensturz-espresso\/kassensturz\/online-betrug-deepfakes-und-stimmenklone-locken-opfer-in-die-betrugsfalle?srg_sm_medium=em\" target=\"_blank\" rel=\"noreferrer noopener\">reportage di Kassensturz<\/a> (in tedesco) ha svelato che un cittadino svizzero ha perso 10\u2019000 franchi a causa di un video di questo tipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I deepfake vengono utilizzati anche per l\u2019estorsione sessuale o sextortion: i truffatori realizzano immagini intime false e le usano per ricattare le vittime.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Come proteggersi<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La regola in caso di telefonate mute: se <strong>nessuno parla all\u2019altro capo del filo<\/strong>, <strong>riagganciate immediatamente<\/strong>. Non dite \u00abPronto\u00bb, non fate domande. Non accettate mai videochiamate da numeri sconosciuti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non fatevi <strong>mai mettere sotto pressione<\/strong>. Riagganciate e richiamate la persona al <strong>numero che conoscete<\/strong>. Non utilizzate mai il pulsante di richiamata, perch\u00e9 vi rimetterebbe in contatto con il truffatore. Definite con i vostri familiari una <strong>parola d\u2019ordine per le emergenze<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E non esagerate con i <strong>messaggi vocali e i video sui social media<\/strong>: ogni post pubblicato \u00e8 una potenziale \u00abmateria prima\u00bb per voice cloning e deepfake.<\/p>\n\n\n\n<div class=\"wp-block-group grey box has-background\" style=\"background-color:#f7f7f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading\"><strong>Falsi avvisi di sicurezza via e-mail<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In questo periodo circolano messaggi di phishing apparentemente provenienti da servizi antifrode o dipartimenti di sicurezza, secondo i quali la vostra carta sarebbe stata bloccata. Vi viene chiesto di cliccare su un link per procedere allo sblocco. Il vero obiettivo \u00e8 quello di rubare i dati della vostra carta o i vostri dati di login.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Attenzione:<\/strong> Viseca non vi chieder\u00e0 mai tramite e-mail o SMS di inserire i dati della vostra carta o di cliccare su link per sbloccarla. Le notifiche rilevanti sul piano della sicurezza vi verranno inviate esclusivamente tramite l\u2019app one, oppure verrete invitati a mettervi personalmente in comunicazione con il servizio clienti.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.viseca.ch\/it\/servizi\/sicurezza\/truffa-furto-di-dati\" target=\"_blank\" rel=\"noreferrer noopener\">Tutte le informazioni sulla protezione dalla frode<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 soddisfatto di Viseca? Ci farebbe piacere ricevere la sua recensione su Google. <a href=\"https:\/\/g.page\/r\/CbwEUboVKey0EBM\/review\">Lasci una recensione qui<\/a><\/p>\n\n\n\n    <div class=\"select-post-holder flex-container section layout-article-teaser\">\n     <div class=\"container\">\n       \n                   \n                 \n     <div class=\"select-post flex-item square\">\n                           \n                                 \n                  <div class=\"featured-image-holder\">\n                     <a href=\"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/\">\n                       <div class=\"featured-iamge\">\n                         <img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1-400x400.jpg\" class=\"attachment-mid-size-q size-mid-size-q wp-post-image\" alt=\"\" srcset=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1-400x400.jpg 400w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1-150x150.jpg 150w, https:\/\/www.mycard.ch\/wp-content\/uploads\/2025\/08\/01_header_phishing_SB9_16x9_1759435418-1-200x200.jpg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>                       <\/div>\n                     <\/a>\t\n                   <\/div>\n                   \n                   <div class=\"featured-content\">\n                      <a href=\"https:\/\/www.mycard.ch\/it\/cosi-evitate-di-cadere-nella-trappola-del-phishing\/\">\n                       <h2>Cos\u00ec evitate di cadere nella trappola del phishing<\/h2>\n                       <span class=\"reading-time\"><span class=\"bsf-rt-reading-time\"><span class=\"bsf-rt-display-label\" prefix=\"Reading Time\">\n\t\t<\/span> <span class=\"bsf-rt-display-time\" reading_time=\"2\"><\/span> \n\t\t<span class=\"bsf-rt-display-postfix\" postfix=\"mins\"><\/span><\/span>min. di lettura<\/span>\n                       <\/a>\t\n                  <\/div>\n                     \n                              \n            \n               \n               \n                 \n\n                  <\/div>    \n                      \n                   \n       \n     <\/div> \n   <\/div>  \n","protected":false},"excerpt":{"rendered":"<p>In breve Il telefono squilla. Rispondete: silenzio. Istintivamente dite: \u00abPronto? Chi parla?\u00bb E siete in trappola. I truffatori si servono delle telefonate mute proprio per raccogliere campioni vocali. A un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-7770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maggiore-sicurezza"],"acf":{"show_content_below_image":[],"mobiles_bild":false,"publizieren_auf":["mycard"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA - MyCard<\/title>\n<meta name=\"description\" content=\"I truffatori clonano voci e falsificano video con l&#039;IA. Come riconoscere le chiamate mute, le voci contraffatte e i deepfake e come proteggersi efficacemente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA - MyCard\" \/>\n<meta property=\"og:description\" content=\"I truffatori clonano voci e falsificano video con l&#039;IA. Come riconoscere le chiamate mute, le voci contraffatte e i deepfake e come proteggersi efficacemente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/\" \/>\n<meta property=\"og:site_name\" content=\"MyCard\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T22:01:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_Header_2698735253_1600x900.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bojan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bojan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/\"},\"author\":{\"name\":\"Bojan\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\"},\"headline\":\"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA\",\"datePublished\":\"2026-03-31T22:01:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/\"},\"wordCount\":570,\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/VISE_Cloning_Header_2698735253_1600x900.jpg\",\"articleSection\":[\"Maggiore sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/\",\"name\":\"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA - MyCard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/VISE_Cloning_Header_2698735253_1600x900.jpg\",\"datePublished\":\"2026-03-31T22:01:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\"},\"description\":\"I truffatori clonano voci e falsificano video con l'IA. Come riconoscere le chiamate mute, le voci contraffatte e i deepfake e come proteggersi efficacemente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/VISE_Cloning_Header_2698735253_1600x900.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mycard.ch\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/VISE_Cloning_Header_2698735253_1600x900.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.mycard.ch\\\/\",\"name\":\"MyCard\",\"description\":\"das Kundenmagazin der Viseca Card Services SA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mycard.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mycard.ch\\\/#\\\/schema\\\/person\\\/2bf90bf839410d3bee77b07ab7e17350\",\"name\":\"Bojan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g\",\"caption\":\"Bojan\"},\"url\":\"https:\\\/\\\/www.mycard.ch\\\/it\\\/author\\\/bojan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA - MyCard","description":"I truffatori clonano voci e falsificano video con l'IA. Come riconoscere le chiamate mute, le voci contraffatte e i deepfake e come proteggersi efficacemente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/","og_locale":"it_IT","og_type":"article","og_title":"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA - MyCard","og_description":"I truffatori clonano voci e falsificano video con l'IA. Come riconoscere le chiamate mute, le voci contraffatte e i deepfake e come proteggersi efficacemente.","og_url":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/","og_site_name":"MyCard","article_published_time":"2026-03-31T22:01:00+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_Header_2698735253_1600x900.jpg","type":"image\/jpeg"}],"author":"Bojan","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Bojan","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/#article","isPartOf":{"@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/"},"author":{"name":"Bojan","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"headline":"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA","datePublished":"2026-03-31T22:01:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/"},"wordCount":570,"image":{"@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_Header_2698735253_1600x900.jpg","articleSection":["Maggiore sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/","url":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/","name":"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA - MyCard","isPartOf":{"@id":"https:\/\/www.mycard.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/#primaryimage"},"image":{"@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_Header_2698735253_1600x900.jpg","datePublished":"2026-03-31T22:01:00+00:00","author":{"@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350"},"description":"I truffatori clonano voci e falsificano video con l'IA. Come riconoscere le chiamate mute, le voci contraffatte e i deepfake e come proteggersi efficacemente.","breadcrumb":{"@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/#primaryimage","url":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_Header_2698735253_1600x900.jpg","contentUrl":"https:\/\/www.mycard.ch\/wp-content\/uploads\/2026\/03\/VISE_Cloning_Header_2698735253_1600x900.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.mycard.ch\/geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.mycard.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Voci clonate, volti falsificati: come proteggersi dalle frodi basate sull\u2019IA"}]},{"@type":"WebSite","@id":"https:\/\/www.mycard.ch\/#website","url":"https:\/\/www.mycard.ch\/","name":"MyCard","description":"das Kundenmagazin der Viseca Card Services SA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mycard.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.mycard.ch\/#\/schema\/person\/2bf90bf839410d3bee77b07ab7e17350","name":"Bojan","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ac6150a15edeb7f3f21935221658c9422f5d2edc3bf33bbc3ea997464f70d1d?s=96&d=mm&r=g","caption":"Bojan"},"url":"https:\/\/www.mycard.ch\/it\/author\/bojan\/"}]}},"wpml_translations":{"de":{"id":"7762","lang":"de","slug":"geklonte-stimmen-gefaelschte-gesichter-so-schuetzen-sie-sich-vor-ki-betrug"},"fr":{"id":"7767","lang":"fr","slug":"voix-clonees-visages-falsifies-comment-se-proteger-de-la-fraude-a-l-ia"},"it":{"id":"7770","lang":"it","slug":"voci-clonate-volti-falsificati-come-proteggersi-dalle-frodi-basate-sull-ia"}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:55:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/7770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/comments?post=7770"}],"version-history":[{"count":2,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/7770\/revisions"}],"predecessor-version":[{"id":7777,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/posts\/7770\/revisions\/7777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/media\/7763"}],"wp:attachment":[{"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/media?parent=7770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/categories?post=7770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mycard.ch\/it\/wp-json\/wp\/v2\/tags?post=7770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}